{"id":408,"date":"2022-02-02T15:13:49","date_gmt":"2022-02-02T15:13:49","guid":{"rendered":"https:\/\/studiobampo.wgcomunicazione.it\/?p=408"},"modified":"2024-03-21T16:31:28","modified_gmt":"2024-03-21T16:31:28","slug":"nuovo-patent-box-e-possibilita-di-recuperare-i-costi-di-rd-fino-al-2013","status":"publish","type":"post","link":"https:\/\/studiobampo.it\/en\/nuovo-patent-box-e-possibilita-di-recuperare-i-costi-di-rd-fino-al-2013\/","title":{"rendered":"Nuovo Patent Box e possibilit\u00e0 di &#8220;recuperare&#8221; i costi di R&#038;D fino al 2013"},"content":{"rendered":"<div data-breakout=\"normal\">\n<p id=\"viewer-foo\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">Il nuovo regime Patent Box <\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block1\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-2psbd\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">La Legge di bilancio 2022 ha riscritto buona parte del regime del patent box per le imprese.<\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block2\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-fklo0\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">Nel nuovo regime vengono esclusi i marchi d&#8217;impresa e il \u201cknow-how\u201d; \u00e8 stata prevista solo una maxi-deduzione dei costi di ricerca e sviluppo, al 110%, e la cancellazione del divieto di cumulo, in relazione ai medesimi costi, dell&#8217;agevolazione con il credito d&#8217;imposta per le attivit\u00e0 di ricerca e sviluppo.<\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block3\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-a4r72\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">Il nuovo regime di maxi-deduzione delle spese di ricerca e sviluppo si rende applicabile con riferimento al periodo di imposta in corso alla data di entrata in vigore del \u201cDL Fiscale\u201d (22 ottobre 2021).<\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block4\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-39elb\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">Con Provvedimento del Direttore dell&#8217;Agenzia delle Entrate saranno adottate le disposizioni attuative del nuovo regime. \u00c8 importante che vengano declinate con precisione le spese che danno diritto all&#8217;agevolazione, tenuto conto della diversa tipologia di attivit\u00e0 di ricerca e sviluppo ritenute agevolabili.<\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block5\"><\/div>\n<div data-breakout=\"normal\">\n<div id=\"viewer-algcb\" class=\"_9-O5y h4vUg KNByY TI-xX\"><span class=\"_1N6tE\">\u00a0<\/span><\/div>\n<\/div>\n<div data-hook=\"rcv-block6\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-78jae\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">Il nuovo regime trova applicazione con riferimento ai seguenti beni utilizzati direttamente o indirettamente nello svolgimento della propria attivit\u00e0 di impresa:<\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block7\"><\/div>\n<div data-breakout=\"normal\">\n<ul class=\"_9IweU iPC6I\">\n<li class=\"Ojm1O KNByY\" dir=\"auto\">\n<div>\n<p id=\"viewer-dklus\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">software coperto da copyright;<\/span><\/p>\n<\/div>\n<\/li>\n<li class=\"Ojm1O KNByY\" dir=\"auto\">\n<div>\n<p id=\"viewer-bn5mf\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">brevetti industriali;<\/span><\/p>\n<\/div>\n<\/li>\n<li class=\"Ojm1O KNByY\" dir=\"auto\">\n<div>\n<p id=\"viewer-d9g2t\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">disegni e modelli.<\/span><\/p>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div data-hook=\"rcv-block8\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-5scj8\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">Le attivit\u00e0 di ricerca e sviluppo possono essere svolte internamente o anche mediante contratti di ricerca stipulati con societ\u00e0 diverse da quelle che direttamente o indirettamente controllano l&#8217;impresa, ne sono controllate o sono controllate dalla stessa societ\u00e0 che controlla l&#8217;impresa, o ancora con universit\u00e0 o enti di ricerca e organismi equiparati.<\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block9\"><\/div>\n<div data-breakout=\"normal\">\n<div id=\"viewer-6lkoq\" class=\"_9-O5y h4vUg KNByY TI-xX\"><span class=\"_1N6tE\">\u00a0<\/span><\/div>\n<\/div>\n<div data-hook=\"rcv-block10\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-2qmun\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">Il recapture dei costi fino al 2013<\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block11\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-1nd1i\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">La legge di bilancio 2022 ha, inoltre, previsto un meccanismo di recapture su base \u201cottennale\u201d, che consente di recuperare il beneficio non utilizzato in relazione alle spese di ricerca e sviluppo che, ex post, hanno dato vita a un bene immateriale. In particolare, qualora in uno o pi\u00f9 periodi d&#8217;imposta siano sostenute spese di ricerca e sviluppo in vista della creazione di uno o pi\u00f9 immobilizzazioni immateriali agevolabili, il contribuente pu\u00f2 fruire della maggiorazione del 110% delle spese a decorrere dal periodo d&#8217;imposta in cui l&#8217;immobilizzazione immateriale ottiene un titolo di \u201cprivativa industriale\u201d (art. 6 c. 10-bis \u201cDL Fiscale\u201d).<\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block12\"><\/div>\n<div data-breakout=\"normal\">\n<div id=\"viewer-cjcgv\" class=\"_9-O5y h4vUg KNByY TI-xX\"><span class=\"_1N6tE\">\u00a0<\/span><\/div>\n<\/div>\n<div data-hook=\"rcv-block13\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-2c3kg\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">La maggiorazione del 110% non pu\u00f2 essere applicata alle spese sostenute prima dell&#8217;ottavo periodo d&#8217;imposta antecedente a quello nel quale l&#8217;immobilizzazione immateriale ottiene il cennato titolo di \u201cprivativa industriale\u201d.<\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block14\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-fvclt\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">Pur nel silenzio della norma, stante i chiarimenti contenuti nella Relazione tecnica al maxi-emendamento alla Legge di bilancio 2022, nel calcolo delle spese sostenute negli otto anni anteriori a quello di ottenimento della \u201cprivativa industriale\u201d si ritiene possano essere incluse anche quelle anteriori al 2021 (anno di entrata in vigore del nuovo regime).<\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block15\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-36o2o\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">Ad analoghe conclusioni \u00e8 giunta l&#8217;Agenzia delle Entrate nel corso di Telefisco 2022.<\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block16\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-37c7v\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">Il caso esaminato ha riguardato un&#8217;immobilizzazione immateriale che ha ottenuto il titolo di \u201cprivativa industriale\u201d nel 2021. Sul punto, \u00e8 stato confermato che l&#8217;impresa pu\u00f2 recuperare la maggiorazione dei costi ricerca e sviluppo sostenuti a partire dal 2013 (ottavo anno d&#8217;imposta precedente quello di ottenimento della \u201cprivativa industriale\u201d).<\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block17\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-635t7\" class=\"_9-O5y h4vUg KNByY iPC6I TI-xX\"><span class=\"_1N6tE\">In termini generali, con il termine \u201cprivativa industriale\u201d deve intendersi la protezione accordata dalla legge agli autori di nuove invenzioni o scoperte industriali. Si dovrebbero, quindi, ritenere agevolabili anche i disegni e modelli non registrati ma comunque \u201cgiuridicamente tutelabili\u201d in applicazione della normativa comunitaria.<\/span><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Il nuovo regime Patent Box La Legge di bilancio 2022 ha riscritto buona parte del regime del patent box per le imprese. Nel nuovo regime vengono esclusi i marchi d&#8217;impresa e il \u201cknow-how\u201d; \u00e8 stata prevista solo una maxi-deduzione dei costi di ricerca e sviluppo, al 110%, e la cancellazione del divieto di cumulo, in [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"footnotes":""},"categories":[7],"tags":[],"class_list":["post-408","post","type-post","status-publish","format-standard","category-novita"],"_links":{"self":[{"href":"https:\/\/studiobampo.it\/en\/wp-json\/wp\/v2\/posts\/408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/studiobampo.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/studiobampo.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/studiobampo.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/studiobampo.it\/en\/wp-json\/wp\/v2\/comments?post=408"}],"version-history":[{"count":1,"href":"https:\/\/studiobampo.it\/en\/wp-json\/wp\/v2\/posts\/408\/revisions"}],"predecessor-version":[{"id":411,"href":"https:\/\/studiobampo.it\/en\/wp-json\/wp\/v2\/posts\/408\/revisions\/411"}],"wp:attachment":[{"href":"https:\/\/studiobampo.it\/en\/wp-json\/wp\/v2\/media?parent=408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/studiobampo.it\/en\/wp-json\/wp\/v2\/categories?post=408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/studiobampo.it\/en\/wp-json\/wp\/v2\/tags?post=408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}